{"id":73716,"date":"2025-01-22T12:59:28","date_gmt":"2025-01-22T11:59:28","guid":{"rendered":"https:\/\/gronau-inside.de\/eig_news\/puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech"},"modified":"2025-01-22T12:59:28","modified_gmt":"2025-01-22T11:59:28","slug":"puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech","status":"publish","type":"eig_news","link":"https:\/\/gronau-inside.de\/nl\/eig_news\/puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech","title":{"rendered":"Puh, der Januar ist ganz sch\u00f6n teuer, oder? \ud83d\ude48\nLanden bei euch auch viele Rech&#8230;"},"content":{"rendered":"<p>Puh, der Januar ist ganz sch\u00f6n teuer, oder? \ud83d\ude48<br \/>\nLanden bei euch auch viele Rechnungen (GEZ, Versicherungen, Nachzahlungen&#8230;)? Dann haben wir was f\u00fcr euch! \ud83d\udc4f<br \/>\nFolgt unserer Seite und schickt uns bis n\u00e4chsten Dienstag, den 28. Januar 2025, eure Rechnungen (einfach als PN) und habt die Chance, einen Stadtgutschein in gleicher H\u00f6he zu gewinnen!<\/p>\n<p>Der Gewinner wird am Mittwochmorgen ausgelost und auf Instagram sowie Facebook bekanntgegeben. Viel Gl\u00fcck! \ud83d\udecd\ud83c\udf40<br \/>\nPS: Markiert gerne Freunde, Familie oder Bekannte, die auch von der Aktion profitieren k\u00f6nnten! \ud83d\ude0a<\/p>\n","protected":false},"featured_media":73713,"template":"","categories":[],"class_list":["post-73716","eig_news","type-eig_news","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Puh, der Januar ist ganz sch\u00f6n teuer, oder? \ud83d\ude48 Landen bei euch auch viele Rech... - Gronau Inside<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gronau-inside.de\/nl\/eig_news\/puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Puh, der Januar ist ganz sch\u00f6n teuer, oder? \ud83d\ude48 Landen bei euch auch viele Rech... - Gronau Inside\" \/>\n<meta property=\"og:description\" content=\"Puh, der Januar ist ganz sch\u00f6n teuer, oder? \ud83d\ude48 Landen bei euch auch viele Rechnungen (GEZ, Versicherungen, Nachzahlungen&#8230;)? Dann haben wir was f\u00fcr euch! \ud83d\udc4f Folgt unserer Seite und schickt [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gronau-inside.de\/nl\/eig_news\/puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech\" \/>\n<meta property=\"og:site_name\" content=\"Gronau Inside\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl\\\/eig_news\\\/puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech\",\"url\":\"https:\\\/\\\/gronau-inside.de\\\/nl\\\/eig_news\\\/puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech\",\"name\":\"Puh, der Januar ist ganz sch\u00f6n teuer, oder? \ud83d\ude48 Landen bei euch auch viele Rech... - Gronau Inside\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl\\\/eig_news\\\/puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl\\\/eig_news\\\/puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gronau-inside.de\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/473374109_1192351372895629_6381280926753478570_n.jpg\",\"datePublished\":\"2025-01-22T11:59:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl\\\/eig_news\\\/puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gronau-inside.de\\\/nl\\\/eig_news\\\/puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl\\\/eig_news\\\/puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech#primaryimage\",\"url\":\"https:\\\/\\\/gronau-inside.de\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/473374109_1192351372895629_6381280926753478570_n.jpg\",\"contentUrl\":\"https:\\\/\\\/gronau-inside.de\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/473374109_1192351372895629_6381280926753478570_n.jpg\",\"width\":720,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl\\\/eig_news\\\/puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/gronau-inside.de\\\/nl\\\/startseite\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Puh, der Januar ist ganz sch\u00f6n teuer, oder? \ud83d\ude48 Landen bei euch auch viele Rech&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl#website\",\"url\":\"https:\\\/\\\/gronau-inside.de\\\/nl\",\"name\":\"Gronau Inside\",\"description\":\"Musikstadt im Gr\u00fcnen\",\"publisher\":{\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gronau-inside.de\\\/nl?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl#organization\",\"name\":\"Gronau Inside\",\"url\":\"https:\\\/\\\/gronau-inside.de\\\/nl\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gronau-inside.de\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/01_gronau-logo_weissaufweiss_Schriftzug-1.png\",\"contentUrl\":\"https:\\\/\\\/gronau-inside.de\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/01_gronau-logo_weissaufweiss_Schriftzug-1.png\",\"width\":254,\"height\":246,\"caption\":\"Gronau Inside\"},\"image\":{\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Puh, der Januar ist ganz sch\u00f6n teuer, oder? \ud83d\ude48 Landen bei euch auch viele Rech... - Gronau Inside","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gronau-inside.de\/nl\/eig_news\/puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech","og_locale":"nl_NL","og_type":"article","og_title":"Puh, der Januar ist ganz sch\u00f6n teuer, oder? \ud83d\ude48 Landen bei euch auch viele Rech... - Gronau Inside","og_description":"Puh, der Januar ist ganz sch\u00f6n teuer, oder? \ud83d\ude48 Landen bei euch auch viele Rechnungen (GEZ, Versicherungen, Nachzahlungen&#8230;)? Dann haben wir was f\u00fcr euch! \ud83d\udc4f Folgt unserer Seite und schickt [&hellip;]","og_url":"https:\/\/gronau-inside.de\/nl\/eig_news\/puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech","og_site_name":"Gronau Inside","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gronau-inside.de\/nl\/eig_news\/puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech","url":"https:\/\/gronau-inside.de\/nl\/eig_news\/puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech","name":"Puh, der Januar ist ganz sch\u00f6n teuer, oder? \ud83d\ude48 Landen bei euch auch viele Rech... - Gronau Inside","isPartOf":{"@id":"https:\/\/gronau-inside.de\/nl#website"},"primaryImageOfPage":{"@id":"https:\/\/gronau-inside.de\/nl\/eig_news\/puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech#primaryimage"},"image":{"@id":"https:\/\/gronau-inside.de\/nl\/eig_news\/puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech#primaryimage"},"thumbnailUrl":"https:\/\/gronau-inside.de\/wp-content\/uploads\/2025\/01\/473374109_1192351372895629_6381280926753478570_n.jpg","datePublished":"2025-01-22T11:59:28+00:00","breadcrumb":{"@id":"https:\/\/gronau-inside.de\/nl\/eig_news\/puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gronau-inside.de\/nl\/eig_news\/puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/gronau-inside.de\/nl\/eig_news\/puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech#primaryimage","url":"https:\/\/gronau-inside.de\/wp-content\/uploads\/2025\/01\/473374109_1192351372895629_6381280926753478570_n.jpg","contentUrl":"https:\/\/gronau-inside.de\/wp-content\/uploads\/2025\/01\/473374109_1192351372895629_6381280926753478570_n.jpg","width":720,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/gronau-inside.de\/nl\/eig_news\/puh-der-januar-ist-ganz-schoen-teuer-oder-%f0%9f%99%88landen-bei-euch-auch-viele-rech#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/gronau-inside.de\/nl\/startseite"},{"@type":"ListItem","position":2,"name":"Puh, der Januar ist ganz sch\u00f6n teuer, oder? \ud83d\ude48 Landen bei euch auch viele Rech&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/gronau-inside.de\/nl#website","url":"https:\/\/gronau-inside.de\/nl","name":"Gronau Inside","description":"Musikstadt im Gr\u00fcnen","publisher":{"@id":"https:\/\/gronau-inside.de\/nl#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gronau-inside.de\/nl?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/gronau-inside.de\/nl#organization","name":"Gronau Inside","url":"https:\/\/gronau-inside.de\/nl","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/gronau-inside.de\/nl#\/schema\/logo\/image\/","url":"https:\/\/gronau-inside.de\/wp-content\/uploads\/2020\/10\/01_gronau-logo_weissaufweiss_Schriftzug-1.png","contentUrl":"https:\/\/gronau-inside.de\/wp-content\/uploads\/2020\/10\/01_gronau-logo_weissaufweiss_Schriftzug-1.png","width":254,"height":246,"caption":"Gronau Inside"},"image":{"@id":"https:\/\/gronau-inside.de\/nl#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/gronau-inside.de\/nl\/wp-json\/wp\/v2\/eig_news\/73716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gronau-inside.de\/nl\/wp-json\/wp\/v2\/eig_news"}],"about":[{"href":"https:\/\/gronau-inside.de\/nl\/wp-json\/wp\/v2\/types\/eig_news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gronau-inside.de\/nl\/wp-json\/wp\/v2\/media\/73713"}],"wp:attachment":[{"href":"https:\/\/gronau-inside.de\/nl\/wp-json\/wp\/v2\/media?parent=73716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gronau-inside.de\/nl\/wp-json\/wp\/v2\/categories?post=73716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}