{"id":94211,"date":"2026-05-13T14:02:45","date_gmt":"2026-05-13T12:02:45","guid":{"rendered":"https:\/\/gronau-inside.de\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta"},"modified":"2026-05-13T14:02:45","modified_gmt":"2026-05-13T12:02:45","slug":"schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta","status":"publish","type":"post","link":"https:\/\/gronau-inside.de\/nl\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta","title":{"rendered":"Sch\u00fctzenfest feiern, jedes Jahr 3 Tage lang, Sch\u00fctzenfest feiern&#8230;.\ud83e\udd73\nWir sta&#8230;"},"content":{"rendered":"<p>Sch\u00fctzenfest feiern, jedes Jahr 3 Tage lang, Sch\u00fctzenfest feiern&#8230;.\ud83e\udd73<br \/>\nWir starten in die Sch\u00fctzenfestsaison. Los geht&#8217;s morgen mit dem Sch\u00fctzenfest St. Katharina. Horrido!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sch\u00fctzenfest feiern, jedes Jahr 3 Tage lang, Sch\u00fctzenfest feiern&#8230;.\ud83e\udd73 Wir starten in die Sch\u00fctzenfestsaison. Los geht&#8217;s morgen mit dem Sch\u00fctzenfest St. Katharina. Horrido!<\/p>\n","protected":false},"author":2,"featured_media":94210,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-94211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-angesagt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sch\u00fctzenfest feiern, jedes Jahr 3 Tage lang, Sch\u00fctzenfest feiern....\ud83e\udd73 Wir sta... - Gronau Inside<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gronau-inside.de\/nl\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sch\u00fctzenfest feiern, jedes Jahr 3 Tage lang, Sch\u00fctzenfest feiern....\ud83e\udd73 Wir sta... - Gronau Inside\" \/>\n<meta property=\"og:description\" content=\"Sch\u00fctzenfest feiern, jedes Jahr 3 Tage lang, Sch\u00fctzenfest feiern&#8230;.\ud83e\udd73 Wir starten in die Sch\u00fctzenfestsaison. Los geht&#8217;s morgen mit dem Sch\u00fctzenfest St. Katharina. Horrido!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gronau-inside.de\/nl\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta\" \/>\n<meta property=\"og:site_name\" content=\"Gronau Inside\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T12:02:45+00:00\" \/>\n<meta name=\"author\" content=\"Gronau Inside\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gronau Inside\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl\\\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl\\\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta\"},\"author\":{\"name\":\"Gronau Inside\",\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl#\\\/schema\\\/person\\\/f2e1f5c91cd43ca8b12ddf26d7546e29\"},\"headline\":\"Sch\u00fctzenfest feiern, jedes Jahr 3 Tage lang, Sch\u00fctzenfest feiern&#8230;.\ud83e\udd73 Wir sta&#8230;\",\"datePublished\":\"2026-05-13T12:02:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl\\\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta\"},\"wordCount\":39,\"publisher\":{\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl\\\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gronau-inside.de\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/698381235_1554541873343240_4774166917987357354_n.jpg\",\"articleSection\":[\"#ANGESAGT\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl\\\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta\",\"url\":\"https:\\\/\\\/gronau-inside.de\\\/nl\\\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta\",\"name\":\"Sch\u00fctzenfest feiern, jedes Jahr 3 Tage lang, Sch\u00fctzenfest feiern....\ud83e\udd73 Wir sta... - Gronau Inside\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl\\\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl\\\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gronau-inside.de\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/698381235_1554541873343240_4774166917987357354_n.jpg\",\"datePublished\":\"2026-05-13T12:02:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl\\\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gronau-inside.de\\\/nl\\\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl\\\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta#primaryimage\",\"url\":\"https:\\\/\\\/gronau-inside.de\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/698381235_1554541873343240_4774166917987357354_n.jpg\",\"contentUrl\":\"https:\\\/\\\/gronau-inside.de\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/698381235_1554541873343240_4774166917987357354_n.jpg\",\"width\":720,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl\\\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/gronau-inside.de\\\/nl\\\/startseite\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sch\u00fctzenfest feiern, jedes Jahr 3 Tage lang, Sch\u00fctzenfest feiern&#8230;.\ud83e\udd73 Wir sta&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl#website\",\"url\":\"https:\\\/\\\/gronau-inside.de\\\/nl\",\"name\":\"Gronau Inside\",\"description\":\"Musikstadt im Gr\u00fcnen\",\"publisher\":{\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gronau-inside.de\\\/nl?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl#organization\",\"name\":\"Gronau Inside\",\"url\":\"https:\\\/\\\/gronau-inside.de\\\/nl\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gronau-inside.de\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/01_gronau-logo_weissaufweiss_Schriftzug-1.png\",\"contentUrl\":\"https:\\\/\\\/gronau-inside.de\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/01_gronau-logo_weissaufweiss_Schriftzug-1.png\",\"width\":254,\"height\":246,\"caption\":\"Gronau Inside\"},\"image\":{\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gronau-inside.de\\\/nl#\\\/schema\\\/person\\\/f2e1f5c91cd43ca8b12ddf26d7546e29\",\"name\":\"Gronau Inside\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sch\u00fctzenfest feiern, jedes Jahr 3 Tage lang, Sch\u00fctzenfest feiern....\ud83e\udd73 Wir sta... - Gronau Inside","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gronau-inside.de\/nl\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta","og_locale":"nl_NL","og_type":"article","og_title":"Sch\u00fctzenfest feiern, jedes Jahr 3 Tage lang, Sch\u00fctzenfest feiern....\ud83e\udd73 Wir sta... - Gronau Inside","og_description":"Sch\u00fctzenfest feiern, jedes Jahr 3 Tage lang, Sch\u00fctzenfest feiern&#8230;.\ud83e\udd73 Wir starten in die Sch\u00fctzenfestsaison. Los geht&#8217;s morgen mit dem Sch\u00fctzenfest St. Katharina. Horrido!","og_url":"https:\/\/gronau-inside.de\/nl\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta","og_site_name":"Gronau Inside","article_published_time":"2026-05-13T12:02:45+00:00","author":"Gronau Inside","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"Gronau Inside"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gronau-inside.de\/nl\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta#article","isPartOf":{"@id":"https:\/\/gronau-inside.de\/nl\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta"},"author":{"name":"Gronau Inside","@id":"https:\/\/gronau-inside.de\/nl#\/schema\/person\/f2e1f5c91cd43ca8b12ddf26d7546e29"},"headline":"Sch\u00fctzenfest feiern, jedes Jahr 3 Tage lang, Sch\u00fctzenfest feiern&#8230;.\ud83e\udd73 Wir sta&#8230;","datePublished":"2026-05-13T12:02:45+00:00","mainEntityOfPage":{"@id":"https:\/\/gronau-inside.de\/nl\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta"},"wordCount":39,"publisher":{"@id":"https:\/\/gronau-inside.de\/nl#organization"},"image":{"@id":"https:\/\/gronau-inside.de\/nl\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta#primaryimage"},"thumbnailUrl":"https:\/\/gronau-inside.de\/wp-content\/uploads\/2026\/05\/698381235_1554541873343240_4774166917987357354_n.jpg","articleSection":["#ANGESAGT"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/gronau-inside.de\/nl\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta","url":"https:\/\/gronau-inside.de\/nl\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta","name":"Sch\u00fctzenfest feiern, jedes Jahr 3 Tage lang, Sch\u00fctzenfest feiern....\ud83e\udd73 Wir sta... - Gronau Inside","isPartOf":{"@id":"https:\/\/gronau-inside.de\/nl#website"},"primaryImageOfPage":{"@id":"https:\/\/gronau-inside.de\/nl\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta#primaryimage"},"image":{"@id":"https:\/\/gronau-inside.de\/nl\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta#primaryimage"},"thumbnailUrl":"https:\/\/gronau-inside.de\/wp-content\/uploads\/2026\/05\/698381235_1554541873343240_4774166917987357354_n.jpg","datePublished":"2026-05-13T12:02:45+00:00","breadcrumb":{"@id":"https:\/\/gronau-inside.de\/nl\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gronau-inside.de\/nl\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/gronau-inside.de\/nl\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta#primaryimage","url":"https:\/\/gronau-inside.de\/wp-content\/uploads\/2026\/05\/698381235_1554541873343240_4774166917987357354_n.jpg","contentUrl":"https:\/\/gronau-inside.de\/wp-content\/uploads\/2026\/05\/698381235_1554541873343240_4774166917987357354_n.jpg","width":720,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/gronau-inside.de\/nl\/schuetzenfest-feiern-jedes-jahr-3-tage-lang-schuetzenfest-feiern-%f0%9f%a5%b3wir-sta#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/gronau-inside.de\/nl\/startseite"},{"@type":"ListItem","position":2,"name":"Sch\u00fctzenfest feiern, jedes Jahr 3 Tage lang, Sch\u00fctzenfest feiern&#8230;.\ud83e\udd73 Wir sta&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/gronau-inside.de\/nl#website","url":"https:\/\/gronau-inside.de\/nl","name":"Gronau Inside","description":"Musikstadt im Gr\u00fcnen","publisher":{"@id":"https:\/\/gronau-inside.de\/nl#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gronau-inside.de\/nl?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/gronau-inside.de\/nl#organization","name":"Gronau Inside","url":"https:\/\/gronau-inside.de\/nl","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/gronau-inside.de\/nl#\/schema\/logo\/image\/","url":"https:\/\/gronau-inside.de\/wp-content\/uploads\/2020\/10\/01_gronau-logo_weissaufweiss_Schriftzug-1.png","contentUrl":"https:\/\/gronau-inside.de\/wp-content\/uploads\/2020\/10\/01_gronau-logo_weissaufweiss_Schriftzug-1.png","width":254,"height":246,"caption":"Gronau Inside"},"image":{"@id":"https:\/\/gronau-inside.de\/nl#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/gronau-inside.de\/nl#\/schema\/person\/f2e1f5c91cd43ca8b12ddf26d7546e29","name":"Gronau Inside"}]}},"_links":{"self":[{"href":"https:\/\/gronau-inside.de\/nl\/wp-json\/wp\/v2\/posts\/94211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gronau-inside.de\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gronau-inside.de\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gronau-inside.de\/nl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gronau-inside.de\/nl\/wp-json\/wp\/v2\/comments?post=94211"}],"version-history":[{"count":0,"href":"https:\/\/gronau-inside.de\/nl\/wp-json\/wp\/v2\/posts\/94211\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gronau-inside.de\/nl\/wp-json\/wp\/v2\/media\/94210"}],"wp:attachment":[{"href":"https:\/\/gronau-inside.de\/nl\/wp-json\/wp\/v2\/media?parent=94211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gronau-inside.de\/nl\/wp-json\/wp\/v2\/categories?post=94211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gronau-inside.de\/nl\/wp-json\/wp\/v2\/tags?post=94211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}